{"id":116,"date":"2019-12-26T07:07:29","date_gmt":"2019-12-26T07:07:29","guid":{"rendered":"https:\/\/excentureconsulting.com\/index.php\/projects\/"},"modified":"2023-02-04T09:03:09","modified_gmt":"2023-02-04T09:03:09","slug":"projects","status":"publish","type":"page","link":"https:\/\/excentureconsulting.com\/index.php\/projects\/","title":{"rendered":"Cloud"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"116\" class=\"elementor elementor-116\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd02435 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd02435\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44287d0\" data-id=\"44287d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41f59ca aux-appear-watch-animation aux-fade-in-up-1 elementor-widget elementor-widget-aux_modern_heading\" data-id=\"41f59ca\" data-element_type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h6 class=\"aux-modern-heading-primary\"><\/h6><h6 class=\"aux-modern-heading-secondary\"><span class=\"aux-head-before\">We pledge ourselves to<\/span><span class=\"aux-head-highlight\"> outstanding project<\/span><\/h6><\/div>\n        <\/section>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69b8540 aux-appear-watch-animation aux-fade-in-right-1 elementor-widget elementor-widget-aux_recent_portfolios_grid\" data-id=\"69b8540\" data-element_type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;}\" data-widget_type=\"aux_recent_portfolios_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-recent-portfolios aux-parent-au2dff5d22\" style=\"\" ><div id=\"6a9790225e5e0\" data-element-id=\"au2dff5d22\" class=\"aux-portfolio-columns aux-ajax-view aux-isotope-animated aux-isotope-layout aux-layout-grid aux-no-gutter aux-row aux-match-height aux-de-col3 aux-tb-col2 aux-mb-col1 aux-lightbox-gallery\" data-lazyload=\"true\" data-space=\"60\" data-pagination=\"true\" data-deeplink=\"true\" data-slug=\"\" data-perpage=\"9\" data-layout=\"fitRows\" data-reveal-transition-duration=\"600\" data-reveal-between-delay=\"60\" data-hide-transition-duration=\"600\" data-hide-between-delay=\"30\" data-num=\"\" data-order=\"DESC\" data-orderby=\"date\" data-taxonomy=\"\" data-n=\"28e57ad457\"><div class=\"aux-items-loading aux-loading-hide\"><div class=\"aux-loading-loop\"><svg class=\"aux-circle\" width=\"100%\" height=\"100%\" viewBox=\"0 0 42 42\"><circle class=\"aux-stroke-bg\" r=\"20\" cx=\"21\" cy=\"21\" fill=\"none\"><\/circle><circle class=\"aux-progress\" r=\"20\" cx=\"21\" cy=\"21\" fill=\"none\" transform=\"rotate(-90 21 21)\"><\/circle><\/svg><\/div><\/div><div class=\"aux-iso-item aux-loading aux-col\">                        <article class=\"post-89 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-beranding portfolio-cat-marketing portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                            <div class=\"aux-hover-active aux-hover-twoway\">\n                                <div class=\"entry-media aux-frame-darken aux-frame-zoom\">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table\/\"><img width=\"546\" height=\"390\" class=\"aux-attachment aux-featured-image attachment-546.66666666667x390 aux-attachment-id-19 \" alt=\"demo-attachment-1360-watermelon-balloon-on-blue-background-creative-57PNH8Q-3\" data-ratio=\"1.2\" data-original-w=\"780\" sizes=\"auto\" data-srcset=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/watermelon-balloon-on-blue-background-creative-57PNH8Q-3-150x125.jpg 150w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/watermelon-balloon-on-blue-background-creative-57PNH8Q-3-300x249.jpg 300w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/watermelon-balloon-on-blue-background-creative-57PNH8Q-3-768x637.jpg 768w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/watermelon-balloon-on-blue-background-creative-57PNH8Q-3.jpg 547w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/watermelon-balloon-on-blue-background-creative-57PNH8Q-3-770x639.jpg 770w\" data-src=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/watermelon-balloon-on-blue-background-creative-57PNH8Q-3.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                                                <div class=\"aux-overlay-content\">\n                                    <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/watermelon-balloon-on-blue-background-creative-57PNH8Q-3.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"780\" data-original-height = \"390\" data-caption = \"demo-attachment-1360-watermelon-balloon-on-blue-background-creative-57PNH8Q-3\"  class=\"aux-lightbox-btn\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <\/div>\n\n                                                        <div class=\"entry-main\">\n\n                                                                <header class=\"entry-header\">\n                                    <h3 class=\"entry-title\">\n                                        <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table\/\">\n                                            Basket of Flower on table                                        <\/a>\n                                    <\/h3>\n                                <\/header>\n                                                                                                                                <div class=\"entry-info\">\n                                    <span class=\"entry-tax\">\n                                                                                <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio-cat\/beranding\/\" title=\"View all posts in BERANDING\" rel=\"category\" >BERANDING<\/a><a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio-cat\/marketing\/\" title=\"View all posts in MARKETING\" rel=\"category\" >MARKETING<\/a>                                    <\/span>\n                                <\/div>\n                                                                                            <\/div>\n                            \n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                        <article class=\"post-90 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-beranding portfolio-cat-marketing portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                            <div class=\"aux-hover-active aux-hover-twoway\">\n                                <div class=\"entry-media aux-frame-darken aux-frame-zoom\">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-2\/\"><img width=\"546\" height=\"453\" class=\"aux-attachment aux-featured-image attachment-546.66666666667x453.73333333333 aux-attachment-id-20 \" alt=\"demo-attachment-1355-malte-wingen-PDX_a_82obo-unsplash2x-3-1-1\" data-ratio=\"1.2\" data-original-w=\"1200\" sizes=\"auto\" data-srcset=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/malte-wingen-PDX_a_82obo-unsplash2x-3-1-1-150x125.jpg 150w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/malte-wingen-PDX_a_82obo-unsplash2x-3-1-1-300x249.jpg 300w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/malte-wingen-PDX_a_82obo-unsplash2x-3-1-1-768x637.jpg 768w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/malte-wingen-PDX_a_82obo-unsplash2x-3-1-1-1024x850.jpg 1024w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/malte-wingen-PDX_a_82obo-unsplash2x-3-1-1.jpg 547w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/malte-wingen-PDX_a_82obo-unsplash2x-3-1-1-1190x987.jpg 1190w\" data-src=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/malte-wingen-PDX_a_82obo-unsplash2x-3-1-1.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                                                <div class=\"aux-overlay-content\">\n                                    <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/malte-wingen-PDX_a_82obo-unsplash2x-3-1-1.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1200\" data-original-height = \"999\" data-caption = \"demo-attachment-1355-malte-wingen-PDX_a_82obo-unsplash2x-3-1-1\"  class=\"aux-lightbox-btn\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-2\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <\/div>\n\n                                                        <div class=\"entry-main\">\n\n                                                                <header class=\"entry-header\">\n                                    <h3 class=\"entry-title\">\n                                        <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-2\/\">\n                                            Basket of Flower on table                                        <\/a>\n                                    <\/h3>\n                                <\/header>\n                                                                                                                                <div class=\"entry-info\">\n                                    <span class=\"entry-tax\">\n                                                                                <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio-cat\/beranding\/\" title=\"View all posts in BERANDING\" rel=\"category\" >BERANDING<\/a><a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio-cat\/marketing\/\" title=\"View all posts in MARKETING\" rel=\"category\" >MARKETING<\/a>                                    <\/span>\n                                <\/div>\n                                                                                            <\/div>\n                            \n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                        <article class=\"post-91 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-beranding portfolio-cat-marketing portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                            <div class=\"aux-hover-active aux-hover-twoway\">\n                                <div class=\"entry-media aux-frame-darken aux-frame-zoom\">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-3\/\"><img width=\"546\" height=\"453\" class=\"aux-attachment aux-featured-image attachment-546.66666666667x453.73333333333 aux-attachment-id-29 \" alt=\"demo-attachment-799-35mm-80ties-analog-1002638@2x\" data-ratio=\"1.2\" data-original-w=\"1200\" sizes=\"auto\" data-srcset=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/35mm-80ties-analog-1002638@2x-150x125.jpg 150w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/35mm-80ties-analog-1002638@2x-300x249.jpg 300w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/35mm-80ties-analog-1002638@2x-768x637.jpg 768w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/35mm-80ties-analog-1002638@2x-1024x850.jpg 1024w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/35mm-80ties-analog-1002638@2x.jpg 547w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/35mm-80ties-analog-1002638@2x-1190x987.jpg 1190w\" data-src=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/35mm-80ties-analog-1002638@2x.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                                                <div class=\"aux-overlay-content\">\n                                    <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/35mm-80ties-analog-1002638@2x.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1200\" data-original-height = \"999\" data-caption = \"demo-attachment-799-35mm-80ties-analog-1002638@2x\"  class=\"aux-lightbox-btn\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-3\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <\/div>\n\n                                                        <div class=\"entry-main\">\n\n                                                                <header class=\"entry-header\">\n                                    <h3 class=\"entry-title\">\n                                        <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-3\/\">\n                                            Basket of Flower on table                                        <\/a>\n                                    <\/h3>\n                                <\/header>\n                                                                                                                                <div class=\"entry-info\">\n                                    <span class=\"entry-tax\">\n                                                                                <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio-cat\/beranding\/\" title=\"View all posts in BERANDING\" rel=\"category\" >BERANDING<\/a><a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio-cat\/marketing\/\" title=\"View all posts in MARKETING\" rel=\"category\" >MARKETING<\/a>                                    <\/span>\n                                <\/div>\n                                                                                            <\/div>\n                            \n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                        <article class=\"post-92 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-beranding portfolio-cat-marketing portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                            <div class=\"aux-hover-active aux-hover-twoway\">\n                                <div class=\"entry-media aux-frame-darken aux-frame-zoom\">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-4\/\"><img width=\"546\" height=\"453\" class=\"aux-attachment aux-featured-image attachment-546.66666666667x453.73333333333 aux-attachment-id-30 \" alt=\"demo-attachment-796-photo-1429679310900-bad303d0e63a-1@2x\" data-ratio=\"1.2\" data-original-w=\"1200\" sizes=\"auto\" data-srcset=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/photo-1429679310900-bad303d0e63a-1@2x-150x125.jpg 150w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/photo-1429679310900-bad303d0e63a-1@2x-300x249.jpg 300w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/photo-1429679310900-bad303d0e63a-1@2x-768x637.jpg 768w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/photo-1429679310900-bad303d0e63a-1@2x-1024x850.jpg 1024w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/photo-1429679310900-bad303d0e63a-1@2x.jpg 547w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/photo-1429679310900-bad303d0e63a-1@2x-1190x987.jpg 1190w\" data-src=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/photo-1429679310900-bad303d0e63a-1@2x.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                                                <div class=\"aux-overlay-content\">\n                                    <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/photo-1429679310900-bad303d0e63a-1@2x.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1200\" data-original-height = \"999\" data-caption = \"demo-attachment-796-photo-1429679310900-bad303d0e63a-1@2x\"  class=\"aux-lightbox-btn\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-4\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <\/div>\n\n                                                        <div class=\"entry-main\">\n\n                                                                <header class=\"entry-header\">\n                                    <h3 class=\"entry-title\">\n                                        <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-4\/\">\n                                            Basket of Flower on table                                        <\/a>\n                                    <\/h3>\n                                <\/header>\n                                                                                                                                <div class=\"entry-info\">\n                                    <span class=\"entry-tax\">\n                                                                                <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio-cat\/beranding\/\" title=\"View all posts in BERANDING\" rel=\"category\" >BERANDING<\/a><a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio-cat\/marketing\/\" title=\"View all posts in MARKETING\" rel=\"category\" >MARKETING<\/a>                                    <\/span>\n                                <\/div>\n                                                                                            <\/div>\n                            \n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                        <article class=\"post-93 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-beranding portfolio-cat-marketing portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                            <div class=\"aux-hover-active aux-hover-twoway\">\n                                <div class=\"entry-media aux-frame-darken aux-frame-zoom\">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-5\/\"><img width=\"546\" height=\"453\" class=\"aux-attachment aux-featured-image attachment-546.66666666667x453.73333333333 aux-attachment-id-31 \" alt=\"demo-attachment-793-sunglasses-and-striped-retro-hat-PGEBDPR@2x\" data-ratio=\"1.2\" data-original-w=\"1200\" sizes=\"auto\" data-srcset=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/sunglasses-and-striped-retro-hat-PGEBDPR@2x-150x125.jpg 150w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/sunglasses-and-striped-retro-hat-PGEBDPR@2x-300x249.jpg 300w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/sunglasses-and-striped-retro-hat-PGEBDPR@2x-768x637.jpg 768w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/sunglasses-and-striped-retro-hat-PGEBDPR@2x-1024x850.jpg 1024w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/sunglasses-and-striped-retro-hat-PGEBDPR@2x.jpg 547w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/sunglasses-and-striped-retro-hat-PGEBDPR@2x-1190x987.jpg 1190w\" data-src=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/sunglasses-and-striped-retro-hat-PGEBDPR@2x.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                                                <div class=\"aux-overlay-content\">\n                                    <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/sunglasses-and-striped-retro-hat-PGEBDPR@2x.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1200\" data-original-height = \"999\" data-caption = \"demo-attachment-793-sunglasses-and-striped-retro-hat-PGEBDPR@2x\"  class=\"aux-lightbox-btn\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-5\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <\/div>\n\n                                                        <div class=\"entry-main\">\n\n                                                                <header class=\"entry-header\">\n                                    <h3 class=\"entry-title\">\n                                        <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-5\/\">\n                                            Basket of Flower on table                                        <\/a>\n                                    <\/h3>\n                                <\/header>\n                                                                                                                                <div class=\"entry-info\">\n                                    <span class=\"entry-tax\">\n                                                                                <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio-cat\/beranding\/\" title=\"View all posts in BERANDING\" rel=\"category\" >BERANDING<\/a><a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio-cat\/marketing\/\" title=\"View all posts in MARKETING\" rel=\"category\" >MARKETING<\/a>                                    <\/span>\n                                <\/div>\n                                                                                            <\/div>\n                            \n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                        <article class=\"post-94 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-beranding portfolio-cat-marketing portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                            <div class=\"aux-hover-active aux-hover-twoway\">\n                                <div class=\"entry-media aux-frame-darken aux-frame-zoom\">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-6\/\"><img width=\"546\" height=\"453\" class=\"aux-attachment aux-featured-image attachment-546.66666666667x453.73333333333 aux-attachment-id-32 \" alt=\"demo-attachment-790-warren-wong-247290-unsplash@2x\" data-ratio=\"1.2\" data-original-w=\"1200\" sizes=\"auto\" data-srcset=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/warren-wong-247290-unsplash@2x-150x125.jpg 150w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/warren-wong-247290-unsplash@2x-300x249.jpg 300w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/warren-wong-247290-unsplash@2x-768x637.jpg 768w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/warren-wong-247290-unsplash@2x-1024x850.jpg 1024w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/warren-wong-247290-unsplash@2x.jpg 547w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/warren-wong-247290-unsplash@2x-1190x987.jpg 1190w\" data-src=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/warren-wong-247290-unsplash@2x.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                                                <div class=\"aux-overlay-content\">\n                                    <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/warren-wong-247290-unsplash@2x.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1200\" data-original-height = \"999\" data-caption = \"demo-attachment-790-warren-wong-247290-unsplash@2x\"  class=\"aux-lightbox-btn\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-6\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <\/div>\n\n                                                        <div class=\"entry-main\">\n\n                                                                <header class=\"entry-header\">\n                                    <h3 class=\"entry-title\">\n                                        <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-6\/\">\n                                            Basket of Flower on table                                        <\/a>\n                                    <\/h3>\n                                <\/header>\n                                                                                                                                <div class=\"entry-info\">\n                                    <span class=\"entry-tax\">\n                                                                                <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio-cat\/beranding\/\" title=\"View all posts in BERANDING\" rel=\"category\" >BERANDING<\/a><a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio-cat\/marketing\/\" title=\"View all posts in MARKETING\" rel=\"category\" >MARKETING<\/a>                                    <\/span>\n                                <\/div>\n                                                                                            <\/div>\n                            \n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                        <article class=\"post-95 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-uncategorized portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                            <div class=\"aux-hover-active aux-hover-twoway\">\n                                <div class=\"entry-media aux-frame-darken aux-frame-zoom\">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-7\/\"><img width=\"546\" height=\"453\" class=\"aux-attachment aux-featured-image attachment-546.66666666667x453.73333333333 aux-attachment-id-33 \" alt=\"demo-attachment-786-355H@2x\" data-ratio=\"1.2\" data-original-w=\"1200\" sizes=\"auto\" data-srcset=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/355H@2x-150x125.jpg 150w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/355H@2x-300x249.jpg 300w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/355H@2x-768x637.jpg 768w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/355H@2x-1024x850.jpg 1024w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/355H@2x.jpg 547w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/355H@2x-1190x987.jpg 1190w\" data-src=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/355H@2x.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                                                <div class=\"aux-overlay-content\">\n                                    <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/355H@2x.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1200\" data-original-height = \"999\" data-caption = \"demo-attachment-786-355H@2x\"  class=\"aux-lightbox-btn\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-7\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <\/div>\n\n                                                        <div class=\"entry-main\">\n\n                                                                <header class=\"entry-header\">\n                                    <h3 class=\"entry-title\">\n                                        <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-7\/\">\n                                            Basket of Flower on table                                        <\/a>\n                                    <\/h3>\n                                <\/header>\n                                                                                                                                <div class=\"entry-info\">\n                                    <span class=\"entry-tax\">\n                                                                                <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio-cat\/uncategorized\/\" title=\"View all posts in Uncategorized\" rel=\"category\" >Uncategorized<\/a>                                    <\/span>\n                                <\/div>\n                                                                                            <\/div>\n                            \n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                        <article class=\"post-96 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-beranding portfolio-cat-marketing portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                            <div class=\"aux-hover-active aux-hover-twoway\">\n                                <div class=\"entry-media aux-frame-darken aux-frame-zoom\">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-8\/\"><img width=\"546\" height=\"453\" class=\"aux-attachment aux-featured-image attachment-546.66666666667x453.73333333333 aux-attachment-id-34 \" alt=\"demo-attachment-783-brooke-lark-210780@2x\" data-ratio=\"1.2\" data-original-w=\"1200\" sizes=\"auto\" data-srcset=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/brooke-lark-210780@2x-150x125.jpg 150w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/brooke-lark-210780@2x-300x249.jpg 300w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/brooke-lark-210780@2x-768x637.jpg 768w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/brooke-lark-210780@2x-1024x850.jpg 1024w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/brooke-lark-210780@2x.jpg 547w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/brooke-lark-210780@2x-1190x987.jpg 1190w\" data-src=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/brooke-lark-210780@2x.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                                                <div class=\"aux-overlay-content\">\n                                    <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/brooke-lark-210780@2x.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1200\" data-original-height = \"999\" data-caption = \"demo-attachment-783-brooke-lark-210780@2x\"  class=\"aux-lightbox-btn\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-8\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <\/div>\n\n                                                        <div class=\"entry-main\">\n\n                                                                <header class=\"entry-header\">\n                                    <h3 class=\"entry-title\">\n                                        <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-8\/\">\n                                            Basket of Flower on table                                        <\/a>\n                                    <\/h3>\n                                <\/header>\n                                                                                                                                <div class=\"entry-info\">\n                                    <span class=\"entry-tax\">\n                                                                                <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio-cat\/beranding\/\" title=\"View all posts in BERANDING\" rel=\"category\" >BERANDING<\/a><a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio-cat\/marketing\/\" title=\"View all posts in MARKETING\" rel=\"category\" >MARKETING<\/a>                                    <\/span>\n                                <\/div>\n                                                                                            <\/div>\n                            \n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                        <article class=\"post-97 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-beranding portfolio-cat-marketing portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                            <div class=\"aux-hover-active aux-hover-twoway\">\n                                <div class=\"entry-media aux-frame-darken aux-frame-zoom\">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-9\/\"><img width=\"546\" height=\"453\" class=\"aux-attachment aux-featured-image attachment-546.66666666667x453.73333333333 aux-attachment-id-35 \" alt=\"demo-attachment-780-studio-shot-of-white-accessories-on-pink-back-7E4JTGC@2x\" data-ratio=\"1.2\" data-original-w=\"1200\" sizes=\"auto\" data-srcset=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/studio-shot-of-white-accessories-on-pink-back-7E4JTGC@2x-150x125.jpg 150w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/studio-shot-of-white-accessories-on-pink-back-7E4JTGC@2x-300x249.jpg 300w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/studio-shot-of-white-accessories-on-pink-back-7E4JTGC@2x-768x637.jpg 768w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/studio-shot-of-white-accessories-on-pink-back-7E4JTGC@2x-1024x850.jpg 1024w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/studio-shot-of-white-accessories-on-pink-back-7E4JTGC@2x.jpg 547w,https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/studio-shot-of-white-accessories-on-pink-back-7E4JTGC@2x-1190x987.jpg 1190w\" data-src=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/studio-shot-of-white-accessories-on-pink-back-7E4JTGC@2x.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                                                <div class=\"aux-overlay-content\">\n                                    <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/wp-content\/uploads\/2020\/01\/studio-shot-of-white-accessories-on-pink-back-7E4JTGC@2x.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1200\" data-original-height = \"999\" data-caption = \"demo-attachment-780-studio-shot-of-white-accessories-on-pink-back-7E4JTGC@2x\"  class=\"aux-lightbox-btn\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-9\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                                                            <\/div>\n\n                                                        <div class=\"entry-main\">\n\n                                                                <header class=\"entry-header\">\n                                    <h3 class=\"entry-title\">\n                                        <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio\/basket-of-flower-on-table-9\/\">\n                                            Basket of Flower on table                                        <\/a>\n                                    <\/h3>\n                                <\/header>\n                                                                                                                                <div class=\"entry-info\">\n                                    <span class=\"entry-tax\">\n                                                                                <a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio-cat\/beranding\/\" title=\"View all posts in BERANDING\" rel=\"category\" >BERANDING<\/a><a href=\"https:\/\/excentureconsulting.com\/index.php\/portfolio-cat\/marketing\/\" title=\"View all posts in MARKETING\" rel=\"category\" >MARKETING<\/a>                                    <\/span>\n                                <\/div>\n                                                                                            <\/div>\n                            \n                        <\/article>\n<\/div><\/div><script type=\"text\/javascript\">var au2dff5d22AjaxConfig = {\"title\":\"\",\"cat\":[],\"num\":\"\",\"only_posts__in\":\"\",\"include\":\"\",\"exclude\":\"\",\"posts_per_page\":-1,\"offset\":\"\",\"order_by\":\"date\",\"order\":\"DESC\",\"exclude_without_media\":\"yes\",\"display_like\":\"\",\"deeplink\":\"no\",\"use_ajax\":\"no\",\"deeplink_slug\":null,\"show_filters\":\"\",\"filter_by\":null,\"filter_style\":null,\"filter_align\":null,\"reveal_transition_duration\":\"600\",\"reveal_between_delay\":\"60\",\"hide_transition_duration\":\"600\",\"hide_between_delay\":\"30\",\"item_style\":\"classic-lightbox\",\"tile_style_pattern\":\"default\",\"tiles_item_style\":\"overlay\",\"entry_background_color\":\"\",\"entry_border_color\":\"\",\"paginate\":\"yes\",\"perpage\":9,\"crop\":true,\"display_title\":\"yes\",\"show_info\":\"yes\",\"display_read_more\":false,\"image_aspect_ratio\":0.83,\"space\":60,\"desktop_cnum\":\"3\",\"tablet_cnum\":\"2\",\"phone_cnum\":\"1\",\"layout\":\"grid\",\"tag\":\"\",\"filter\":\"\",\"extra_classes\":\"\",\"extra_column_classes\":\"\",\"custom_el_id\":\"\",\"template_part_file\":\"recent-portfolio\",\"extra_template_path\":\"\\\/home\\\/u100328052\\\/domains\\\/excentureconsulting.com\\\/public_html\\\/wp-content\\\/plugins\\\/auxin-portfolio\\\/public\\\/templates\\\/elements\",\"universal_id\":\"au2dff5d22\",\"query_args\":[],\"term\":\"\",\"reset_query\":true,\"use_wp_query\":false,\"wp_query_args\":[],\"custom_wp_query\":\"\",\"loadmore_type\":null,\"loadmore_label\":null,\"loadmore_per_page\":12,\"term_field\":\"slug\",\"base\":\"aux_recent_portfolios_grid\",\"base_class\":\"aux-widget-recent-portfolios\",\"paged\":\"\",\"override_global_query\":false,\"content\":null,\"skip_wrappers\":false,\"content_width\":2000,\"inview_transition\":\"none\",\"inview_duration\":\"\",\"inview_delay\":\"\",\"inview_repeat\":\"no\",\"inview_offset\":\"\",\"called_from\":\"elementor\"};<\/script><\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>We pledge ourselves to outstanding project Basket of Flower on table BERANDINGMARKETING Basket of Flower on table BERANDINGMARKETING Basket of Flower on table BERANDINGMARKETING Basket of Flower on table BERANDINGMARKETING Basket of Flower on table BERANDINGMARKETING Basket of Flower on table BERANDINGMARKETING Basket of Flower on table Uncategorized Basket of Flower on table BERANDINGMARKETING Basket [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/page-builder-content.php","meta":[],"_links":{"self":[{"href":"https:\/\/excentureconsulting.com\/index.php\/wp-json\/wp\/v2\/pages\/116"}],"collection":[{"href":"https:\/\/excentureconsulting.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/excentureconsulting.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/excentureconsulting.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/excentureconsulting.com\/index.php\/wp-json\/wp\/v2\/comments?post=116"}],"version-history":[{"count":1,"href":"https:\/\/excentureconsulting.com\/index.php\/wp-json\/wp\/v2\/pages\/116\/revisions"}],"predecessor-version":[{"id":139,"href":"https:\/\/excentureconsulting.com\/index.php\/wp-json\/wp\/v2\/pages\/116\/revisions\/139"}],"wp:attachment":[{"href":"https:\/\/excentureconsulting.com\/index.php\/wp-json\/wp\/v2\/media?parent=116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}